{"id":5749,"date":"2021-06-16T10:50:00","date_gmt":"2021-06-16T10:50:00","guid":{"rendered":"https:\/\/coisasdevovo.com.br\/?p=5749"},"modified":"2021-06-16T10:50:00","modified_gmt":"2021-06-16T10:50:00","slug":"torta-de-sardinha-a-moda-portuguesa","status":"publish","type":"post","link":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/","title":{"rendered":"Torta de sardinha \u00e0 moda portuguesa"},"content":{"rendered":"<h3>Ingredientes<\/h3>\n<h3>Massa<\/h3>\n<ul>\n<li>250g de farinha de trigo<\/li>\n<li>100 g de manteiga sem sal<\/li>\n<li>1 ovo grande inteiro ou 2 pequenos<\/li>\n<li>1 colher de ch\u00e1 de sal<\/li>\n<li>1 colher de ch\u00e1 de fermento em p\u00f3<\/li>\n<\/ul>\n<h3>Recheio<\/h3>\n<ul>\n<li>1 x\u00edcara de molho de tomate (bem temperadinho!!!)<\/li>\n<li>2 latas de sardinha, eu usei da marca Ramirez, portuguesa, que agora a gente encontra nos supermercados brasileiros. Escolhi as marinadas em molho de tomate picante, mas existem outras op\u00e7\u00f5es.<\/li>\n<li>2 ovos cozidos partidos em quatro<\/li>\n<li>1 tomate em rodelas<\/li>\n<li>1 cebola roxa finamente laminada<\/li>\n<li>2 colheres de salsinha fatiadinha<\/li>\n<li>1 colher de dodo de mo\u00e7a laminada (opcional)<\/li>\n<li>azeite, sal e pimenta do reino \u00e0 gosto.<\/li>\n<\/ul>\n<h3>\u00a0Modo de fazer<\/h3>\n<h3>Massa<\/h3>\n<p>Junte a manteiga gelada \u00e0 farinha com o fermento e o sal. Corte a manteiga com uma faca at\u00e9 ficar com uma farofinha de farinha e manteiga.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Acrescente o ovo (eu fiz duas receitas por isso dois ovos!) e amasse bem at\u00e9 obter com uma massa homog\u00eanea.<\/p>\n<p>Deixe a massa descansar por 20 minutos coberta com um pano de prato.<\/p>\n<h3>Montagem<\/h3>\n<p>Com a ponta dos dedos forre uma assadeira de fundo remov\u00edvel com a massa. Tente fazer com a espessura mais fina que conseguir. Suba com a massa pelas bordas.<\/p>\n<p>Espalhe o molho de tomate (eu fiz com azeite, alho e salsinha, bem temperado e ardidinho).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5750\" src=\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/montagem-torta-de-sardinha-leticia-massula-para-cozinha-damatilde-122x300.jpg\" alt=\"\" width=\"511\" height=\"1257\" srcset=\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/montagem-torta-de-sardinha-leticia-massula-para-cozinha-damatilde-122x300.jpg 122w, https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/montagem-torta-de-sardinha-leticia-massula-para-cozinha-damatilde-416x1024.jpg 416w, https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/montagem-torta-de-sardinha-leticia-massula-para-cozinha-damatilde.jpg 640w\" sizes=\"(max-width: 511px) 100vw, 511px\" \/><\/p>\n<p>Sobre o molho de tomate espalhe as sardinhas amassadas com um garfo.<\/p>\n<p>Sobre ela as rodelas de tomate e os quartos de ovo.<\/p>\n<p>Polvilhe tudo com a cebola, salsinha e pimenta em l\u00e2minas. Finalize com as azeitoninhas e um fio de azeite.<\/p>\n<p>Abra tiras da massa e com elas enfeite a torta fazendo uma trama que pode ser mais aberta ou mais fechada (eu prefiro menos massa, ent\u00e3o fa\u00e7o mais aberta). Se for do seu agrado, pincele a trama com uma gema (eu prefiro sem, n\u00e3o gosto do sabor do ovo queimado, mas a torta fica muito mais bonita).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5751\" src=\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-227x300.jpg\" alt=\"\" width=\"490\" height=\"648\" srcset=\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-227x300.jpg 227w, https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde.jpg 640w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/><\/p>\n<p>Asse em forno pr\u00e9 aquecido por aproximadamente 30 minutos (depende do qu\u00e3o dourada voc\u00ea quer a massa).<\/p>\n<p>Bom apetite!<\/p>\n<p>&nbsp;<\/p>\n<p>fonte-<a href=\"http:\/\/www.cozinhadamatilde.com.br\/comida-de-sogra-torta-de-sardinha-a-moda-portuguesa\/\">Cozinha da Matilde<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes Massa 250g de farinha de trigo 100 g de manteiga sem sal 1 ovo grande inteiro ou 2 pequenos 1 colher de ch\u00e1 de sal 1 colher de ch\u00e1 de fermento em p\u00f3 Recheio 1 x\u00edcara de molho de tomate (bem temperadinho!!!) 2 latas de sardinha, eu usei da marca Ramirez, portuguesa, que agora &hellip; <\/p>\n","protected":false},"author":1,"featured_media":5752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[39],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Torta de sardinha \u00e0 moda portuguesa - Coisas de V\u00f3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torta de sardinha \u00e0 moda portuguesa - Coisas de V\u00f3\" \/>\n<meta property=\"og:description\" content=\"Ingredientes Massa 250g de farinha de trigo 100 g de manteiga sem sal 1 ovo grande inteiro ou 2 pequenos 1 colher de ch\u00e1 de sal 1 colher de ch\u00e1 de fermento em p\u00f3 Recheio 1 x\u00edcara de molho de tomate (bem temperadinho!!!) 2 latas de sardinha, eu usei da marca Ramirez, portuguesa, que agora &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Coisas de V\u00f3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PortalCoisasDeVo\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-16T10:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"845\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jhonatas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jhonatas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/coisasdevovo.com.br\/#website\",\"url\":\"https:\/\/coisasdevovo.com.br\/\",\"name\":\"Coisa de Vo\",\"description\":\"Tudo feito com muito amor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/coisasdevovo.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#primaryimage\",\"url\":\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-1.jpg\",\"contentUrl\":\"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-1.jpg\",\"width\":640,\"height\":845},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/\",\"url\":\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/\",\"name\":\"Torta de sardinha \u00e0 moda portuguesa - Coisas de V\u00f3\",\"isPartOf\":{\"@id\":\"https:\/\/coisasdevovo.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#primaryimage\"},\"datePublished\":\"2021-06-16T10:50:00+00:00\",\"dateModified\":\"2021-06-16T10:50:00+00:00\",\"author\":{\"@id\":\"https:\/\/coisasdevovo.com.br\/#\/schema\/person\/7263fc74988d68b31164113b6e1c53dd\"},\"breadcrumb\":{\"@id\":\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/coisasdevovo.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torta de sardinha \u00e0 moda portuguesa\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/coisasdevovo.com.br\/#\/schema\/person\/7263fc74988d68b31164113b6e1c53dd\",\"name\":\"Jhonatas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/coisasdevovo.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4529793b408d44d4cfeb6fd77b1c2471?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4529793b408d44d4cfeb6fd77b1c2471?s=96&d=mm&r=g\",\"caption\":\"Jhonatas\"},\"url\":\"https:\/\/coisasdevovo.com.br\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torta de sardinha \u00e0 moda portuguesa - Coisas de V\u00f3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/","og_locale":"pt_BR","og_type":"article","og_title":"Torta de sardinha \u00e0 moda portuguesa - Coisas de V\u00f3","og_description":"Ingredientes Massa 250g de farinha de trigo 100 g de manteiga sem sal 1 ovo grande inteiro ou 2 pequenos 1 colher de ch\u00e1 de sal 1 colher de ch\u00e1 de fermento em p\u00f3 Recheio 1 x\u00edcara de molho de tomate (bem temperadinho!!!) 2 latas de sardinha, eu usei da marca Ramirez, portuguesa, que agora &hellip;","og_url":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/","og_site_name":"Coisas de V\u00f3","article_publisher":"https:\/\/www.facebook.com\/PortalCoisasDeVo","article_published_time":"2021-06-16T10:50:00+00:00","og_image":[{"width":640,"height":845,"url":"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-1.jpg","type":"image\/jpeg"}],"author":"Jhonatas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jhonatas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/coisasdevovo.com.br\/#website","url":"https:\/\/coisasdevovo.com.br\/","name":"Coisa de Vo","description":"Tudo feito com muito amor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coisasdevovo.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#primaryimage","url":"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-1.jpg","contentUrl":"https:\/\/coisasdevovo.com.br\/wp-content\/uploads\/2019\/07\/torta-de-sarinha-leticia-massula-para-cozinha-da-matilde-1.jpg","width":640,"height":845},{"@type":"WebPage","@id":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/","url":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/","name":"Torta de sardinha \u00e0 moda portuguesa - Coisas de V\u00f3","isPartOf":{"@id":"https:\/\/coisasdevovo.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#primaryimage"},"datePublished":"2021-06-16T10:50:00+00:00","dateModified":"2021-06-16T10:50:00+00:00","author":{"@id":"https:\/\/coisasdevovo.com.br\/#\/schema\/person\/7263fc74988d68b31164113b6e1c53dd"},"breadcrumb":{"@id":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coisasdevovo.com.br\/index.php\/2021\/06\/16\/torta-de-sardinha-a-moda-portuguesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/coisasdevovo.com.br\/"},{"@type":"ListItem","position":2,"name":"Torta de sardinha \u00e0 moda portuguesa"}]},{"@type":"Person","@id":"https:\/\/coisasdevovo.com.br\/#\/schema\/person\/7263fc74988d68b31164113b6e1c53dd","name":"Jhonatas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coisasdevovo.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4529793b408d44d4cfeb6fd77b1c2471?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4529793b408d44d4cfeb6fd77b1c2471?s=96&d=mm&r=g","caption":"Jhonatas"},"url":"https:\/\/coisasdevovo.com.br\/index.php\/author\/admin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5749"}],"collection":[{"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5749"}],"version-history":[{"count":1,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5749\/revisions"}],"predecessor-version":[{"id":5753,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5749\/revisions\/5753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/media\/5752"}],"wp:attachment":[{"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coisasdevovo.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}